{"id":12638,"date":"2016-10-05T08:38:48","date_gmt":"2016-10-05T08:38:48","guid":{"rendered":"https:\/\/dev.dittaamore.it\/?product=gaia-twister-di-senape-media-da-820-g"},"modified":"2026-07-15T04:54:08","modified_gmt":"2026-07-15T02:54:08","slug":"gaia-twister-di-senape-media-da-820-g","status":"publish","type":"product","link":"https:\/\/dittaamore.it\/en\/prodotto\/gaia-twister-di-senape-media-da-820-g\/","title":{"rendered":"Gaia &#8211; Twister di senape media da 820 g"},"content":{"rendered":"<p><b>La senape media <\/b>\u00e8 per chi ama il gusto classico della tradizione d\u2019oltralpe. La <strong>Senape<\/strong>\u00a0\u00e8 un accompagnamento ideale per le carni rosse alla griglia o lessate e un gustoso contorno per la salsiccia. Intiepidita e guarnita con erbe<br \/>\naromatiche \u00e8 un contorno delizioso per il pesce grigliato o lessato e per le verdure cotte al vapore. La salsa \u00e8 contenuta in un tubettone di plastica da gettare nella raccolta differenziata delle plastica dopo averlo opportunamente risciacquato. Per poter usare i<span id=\"dtx-highlighting-item\">l <\/span>prodotto, non \u00e8 necessario acquistare a parte alcun dispenser specifico. Questo sistema \u00e8 indicato per piccoli utilizzatori. Contenuto: 760 ml.<\/p>\n<p><b>Conservazione:<\/b> Non congelare. Conservare il luogo fresco e asciutto. Una volta aperta la confezione, conservare in frigorifero e consumare entro circa un mese.<\/p>\n<p><b>Ingredienti:<\/b> acqua, semi di senape 20%, aceto di vino, sale, zucchero, spezie, correttore di acidit\u00e0: acido lattico. SENZA GLUTINE.<\/p>\n<p><b>Allergeni:<\/b> pu\u00f2 contenere tracce di uova.<\/p>\n<p><b>Scadenza:<\/b> Il prodotto viene fornito con una vita residua di circa 5\/6 mesi.<\/p>\n<p><strong>Valori nutrizionali medi per 100 g di prodotto<\/strong>: Energia: 494 kj &#8211; 119 kcal, Grassi: 6,5 g, di cui acidi grassi saturi: 0,36 g, Carboidrati: 8,5 g, di cui zuccheri: 3,2 g, Proteine: 5,10 g, Sale: 3,1 g<\/p>\n<p>Il prezzo si riferisce a un Twister da 820 grammi (760 ml).<\/p>\n<p><b>Curiosit\u00e0<\/b>:\u00a0<span style=\"font-style: italic;\">lo sapevate che la senape era usata dagli antichi romani come antiossidante per la conservazione della frutta e della verdura. Le piante di senape raggiungono i due metri di altezza.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La senape media \u00e8 per chi ama il gusto classico della tradizione d\u2019oltralpe. La Senape\u00a0\u00e8 un accompagnamento ideale per le<\/p>\n","protected":false},"featured_media":12640,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[86,564],"product_tag":[],"class_list":["post-12638","product","type-product","status-publish","has-post-thumbnail","product_cat-alimentari-non-bio","product_cat-olio-aceto-salse-e-altri-condimenti","pa_brand-formec-biffi-spa","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"6":4.256},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/product\/12638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/comments?post=12638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/media\/12640"}],"wp:attachment":[{"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/media?parent=12638"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/product_brand?post=12638"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/product_cat?post=12638"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dittaamore.it\/en\/wp-json\/wp\/v2\/product_tag?post=12638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}